{"id":34677,"date":"2026-04-15T15:31:53","date_gmt":"2026-04-15T07:31:53","guid":{"rendered":"https:\/\/eu.felicitysolar.com\/?page_id=34677"},"modified":"2026-05-19T08:41:51","modified_gmt":"2026-05-19T00:41:51","slug":"125kw-ci-energy-storage-solution-2026","status":"publish","type":"page","link":"https:\/\/eu.felicitysolar.com\/la\/125kw-ci-energy-storage-solution-2026\/","title":{"rendered":"125kW C&amp;I Energy Storage Solution 2026"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"34677\" class=\"elementor elementor-34677\" data-elementor-settings=\"{&quot;scroll_snap&quot;:&quot;yes&quot;,&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-122ba1f e-con-full e-flex e-con e-parent\" data-id=\"122ba1f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-1635f3b2 e-con-full e-flex e-con e-child\" data-id=\"1635f3b2\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-5dbd3d9d e-con-full e-flex e-con e-child\" data-id=\"5dbd3d9d\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2957301d elementor-widget-widescreen__width-initial elementor-widget elementor-widget-heading\" data-id=\"2957301d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e81\u0eb2\u0e99\u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 125kW C&amp;I<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254ab0a8 elementor-widget elementor-widget-heading\" data-id=\"254ab0a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e94\u0ec9. \u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0e96\u0eb7\u0ec4\u0e94\u0ec9. \u0eaa\u0ec9\u0eb2\u0e87\u0e82\u0eb6\u0ec9\u0e99\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f80c0e e-con-full e-flex e-con e-child\" data-id=\"3f80c0e\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-305976d e-flex e-con-boxed e-con e-parent\" data-id=\"305976d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6641e8b1 elementor-widget elementor-widget-heading\" data-id=\"6641e8b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0eaa\u0ec9\u0eb2\u0e87\u0e82\u0eb6\u0ec9\u0e99\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-319c2f8a elementor-widget elementor-widget-text-editor\" data-id=\"319c2f8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnscrsiqkv62gwxxdel&quot;,&quot;ind&quot;:{}},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;Flexible system design with dual battery inputs and &quot;],[&quot;span&quot;,{&quot;color&quot;:&quot;&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;10-channel solar charge controllers&quot;],[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot; for stable high-power operation.&quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNjcnNpcWt2NjJnd3h4ZGVsJTIyJTJDJTIyaW5kJTIyJTNBJTdCJTdEJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMnRleHQlMjIlMkMlMjJsZWF2ZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMmxlYWYlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyRmxleGlibGUlMjBzeXN0ZW0lMjBkZXNpZ24lMjB3aXRoJTIwZHVhbCUyMGJhdHRlcnklMjBpbnB1dHMlMjBhbmQlMjAlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU1RCU3RCUyQyU3QiUyMmtsYXNzJTIyJTNBJTIybGVhZiUyMiUyQyUyMnRleHQlMjIlM0ElMjIxMC1jaGFubmVsJTIwc29sYXIlMjBjaGFyZ2UlMjBjb250cm9sbGVycyUyMiUyQyUyMm1hcmtzJTIyJTNBJTVCJTdCJTIya2xhc3MlMjIlM0ElMjJtYXJrJTIyJTJDJTIydHlwZSUyMiUzQSUyMmNvbG9yJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnZhbHVlJTIyJTNBJTIyJTIyJTdEJTdEJTVEJTdEJTJDJTdCJTIya2xhc3MlMjIlM0ElMjJsZWFmJTIyJTJDJTIydGV4dCUyMiUzQSUyMiUyMGZvciUyMHN0YWJsZSUyMGhpZ2gtcG93ZXIlMjBvcGVyYXRpb24uJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlNUQlN0QlNUQlMkMlMjJjb250ZW50VHlwZSUyMiUzQSUyMmNhbmdqaWUtdGV4dGJsb2NrJTIyJTdEJTVEJTdE\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><p style=\"text-align: center;\"><span data-type=\"text\">\u0e81\u0eb2\u0e99\u200b\u0ead\u0ead\u0e81\u200b\u0ec1\u0e9a\u0e9a\u200b\u0ea5\u0eb0\u200b\u0e9a\u0ebb\u0e9a\u200b\u0e97\u0eb5\u0ec8\u200b\u0ea1\u0eb5\u200b\u0e84\u0ea7\u0eb2\u0ea1\u200b\u0ea2\u0eb7\u0e94\u200b\u0ea2\u0eb8\u0ec8\u0e99\u200b\u0e81\u0eb1\u0e9a\u200b\u0e81\u0eb2\u0e99\u200b\u0e9b\u0ec9\u0ead\u0e99\u200b\u0e82\u0ecd\u0ec9\u200b\u0ea1\u0eb9\u0e99\u200b\u0eab\u0ea1\u0ecd\u0ec9\u200b\u0ec4\u0e9f\u200b\u0e84\u0eb9\u0ec8\u200b\u0ec1\u0ea5\u0eb0\u200b <\/span><span data-type=\"text\">\u0e95\u0ebb\u0ea7\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0e81\u0ec4\u0e9f\u0ec1\u0eaa\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99 10 \u0e8a\u0ec8\u0ead\u0e87<\/span><span data-type=\"text\"> \u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e94\u0ecd\u0eb2\u0ec0\u0e99\u0eb5\u0e99\u0e87\u0eb2\u0e99\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0e97\u0eb5\u0ec8\u0eab\u0ea1\u0eb1\u0ec9\u0e99\u0e84\u0ebb\u0e87.<\/span><\/p><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48171b0b e-grid e-con-full e-con e-child\" data-id=\"48171b0b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7a9564 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6b7a9564\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-3.png\" class=\"attachment-medium size-medium wp-image-34695\" alt=\"2 3.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-3.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-3-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">257 kWh<\/h3><p class=\"elementor-image-box-description\">\u0e95\u0ecd\u0ec8\u0e81\u0eb8\u0ec8\u0ea1<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d91ed30 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7d91ed30\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-5.png\" class=\"attachment-medium size-medium wp-image-34697\" alt=\"2 5.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-5.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-5-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">2x<\/h3><p class=\"elementor-image-box-description\">\u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8\u0e9b\u0ec9\u0ead\u0e99\u0ec1\u0e9a\u0eb1\u0e94\u0ec0\u0e95\u0eb5\u0ea3\u0eb5\u0ec1\u0e9a\u0e9a\u0ec0\u0ead\u0e81\u0eb0\u0ea5\u0eb2\u0e94<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38806f75 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"38806f75\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-1.png\" class=\"attachment-thumbnail size-thumbnail wp-image-34693\" alt=\"2 1.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-1.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-1-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">1.5MW<\/h3><p class=\"elementor-image-box-description\">\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e94\u0ec9<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-174a42f8 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"174a42f8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-2.png\" class=\"attachment-medium size-medium wp-image-34694\" alt=\"2 2.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-2.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/2-2-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">98.688MWh<\/h3><p class=\"elementor-image-box-description\">\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb2\u0e94\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e94\u0ec9<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95e3c8c elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"95e3c8c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/05\/2-4-16-Clusters-in-parallel.webp\" class=\"attachment-medium size-medium wp-image-35269\" alt=\"2 4 16 Clusters In Parallel\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/05\/2-4-16-Clusters-in-parallel.webp 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/05\/2-4-16-Clusters-in-parallel-12x12.webp 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">16 \u0e81\u0eb8\u0ec8\u0ea1<\/h3><p class=\"elementor-image-box-description\">\u0ec3\u0e99\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e99<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c107c13 e-flex e-con-boxed e-con e-parent\" data-id=\"c107c13\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-de53238 e-con-full e-flex e-con e-child\" data-id=\"de53238\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-2e8ccf58 e-con-full e-flex e-con e-child\" data-id=\"2e8ccf58\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61e68b66 elementor-widget elementor-widget-heading\" data-id=\"61e68b66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">0ms \u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0eab\u0ebc\u0eb1\u0e9a\u0ec1\u0e9a\u0e9a\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0eae\u0ead\u0e8d\u0e95\u0ecd\u0ec8<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e0ff5a9 elementor-widget elementor-widget-text-editor\" data-id=\"3e0ff5a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnsc8sp1ysy2mchf0aa&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:12,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;With ultra-fast switching capability, the system ensures seamless transition between grid and off-grid modes. &quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNjOHNwMXlzeTJtY2hmMGFhJTIyJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMnRleHQlMjIlMkMlMjJsZWF2ZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMmxlYWYlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyV2l0aCUyMHVsdHJhLWZhc3QlMjBzd2l0Y2hpbmclMjBjYXBhYmlsaXR5JTJDJTIwdGhlJTIwc3lzdGVtJTIwZW5zdXJlcyUyMHNlYW1sZXNzJTIwdHJhbnNpdGlvbiUyMGJldHdlZW4lMjBncmlkJTIwYW5kJTIwb2ZmLWdyaWQlMjBtb2Rlcy4lMjAlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIybWFyayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJzeiUyMiUyQyUyMmRhdGElMjIlM0ElN0IlMjJ2YWx1ZSUyMiUzQTEyJTJDJTIyc3pVbml0JTIyJTNBJTIycHQlMjIlN0QlN0QlNUQlN0QlNUQlN0QlNUQlMkMlMjJjb250ZW50VHlwZSUyMiUzQSUyMmNhbmdqaWUtdGV4dGJsb2NrJTIyJTdEJTVEJTdE\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><p><span data-type=\"text\">\u0e94\u0ec9\u0ea7\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0eab\u0ebc\u0eb1\u0e9a\u0e97\u0eb5\u0ec8\u0ec4\u0ea7\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94, \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e81\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0eab\u0eb1\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2 \u0ec1\u0ea5\u0eb0\u0e99\u0ead\u0e81\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d. <\/span><\/p><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57855fbe e-con-full e-flex e-con e-child\" data-id=\"57855fbe\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b5f2b31 e-con-full e-flex e-con e-parent\" data-id=\"2b5f2b31\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-2e301269 e-con-full e-flex e-con e-child\" data-id=\"2e301269\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-577f4f55 e-con-full e-flex e-con e-child\" data-id=\"577f4f55\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3500499c e-con-full e-flex e-con e-child\" data-id=\"3500499c\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36ab33f2 elementor-widget elementor-widget-heading\" data-id=\"36ab33f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0eaa\u0eb0\u0e96\u0eb2\u0e9b\u0eb1\u0e94\u0e95\u0eb0\u0e8d\u0eb0\u0e81\u0eb3\u0e97\u0eb5\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e94\u0ec9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-246859d3 elementor-widget elementor-widget-text-editor\" data-id=\"246859d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnsc8sp1ysy2mchf0aa&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:12,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;With ultra-fast switching capability, the system ensures seamless transition between grid and off-grid modes. &quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNjOHNwMXlzeTJtY2hmMGFhJTIyJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMnRleHQlMjIlMkMlMjJsZWF2ZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMmxlYWYlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyV2l0aCUyMHVsdHJhLWZhc3QlMjBzd2l0Y2hpbmclMjBjYXBhYmlsaXR5JTJDJTIwdGhlJTIwc3lzdGVtJTIwZW5zdXJlcyUyMHNlYW1sZXNzJTIwdHJhbnNpdGlvbiUyMGJldHdlZW4lMjBncmlkJTIwYW5kJTIwb2ZmLWdyaWQlMjBtb2Rlcy4lMjAlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIybWFyayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJzeiUyMiUyQyUyMmRhdGElMjIlM0ElN0IlMjJ2YWx1ZSUyMiUzQTEyJTJDJTIyc3pVbml0JTIyJTNBJTIycHQlMjIlN0QlN0QlNUQlN0QlNUQlN0QlNUQlMkMlMjJjb250ZW50VHlwZSUyMiUzQSUyMmNhbmdqaWUtdGV4dGJsb2NrJTIyJTdEJTVEJTdE\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnsc8soyvcvsd68182&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:12,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;The IVGM 125kW inverter paired with the FLH HV battery system delivers a scalable solution for commercial and industrial applications.&quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNjOHNveXZjdnNkNjgxODIlMjIlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIydGV4dCUyMiUyQyUyMmxlYXZlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIybGVhZiUyMiUyQyUyMnRleHQlMjIlM0ElMjJUaGUlMjBJVkdNJTIwMTI1a1clMjBpbnZlcnRlciUyMHBhaXJlZCUyMHdpdGglMjB0aGUlMjBGTEglMjBIViUyMGJhdHRlcnklMjBzeXN0ZW0lMjBkZWxpdmVycyUyMGElMjBzY2FsYWJsZSUyMHNvbHV0aW9uJTIwZm9yJTIwY29tbWVyY2lhbCUyMGFuZCUyMGluZHVzdHJpYWwlMjBhcHBsaWNhdGlvbnMuJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMm1hcmslMjIlMkMlMjJ0eXBlJTIyJTNBJTIyc3olMjIlMkMlMjJkYXRhJTIyJTNBJTdCJTIydmFsdWUlMjIlM0ExMiUyQyUyMnN6VW5pdCUyMiUzQSUyMnB0JTIyJTdEJTdEJTVEJTdEJTVEJTdEJTVEJTJDJTIyY29udGVudFR5cGUlMjIlM0ElMjJjYW5namllLXRleHRibG9jayUyMiU3RCU1RCU3RA==\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnsc8sp92e66joh5mzt&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;sz&quot;:12,&quot;szUnit&quot;:&quot;pt&quot;,&quot;data-type&quot;:&quot;leaf&quot;},&quot;The inverter supports parallel connection up to 12 units, and the battery supports 4 parallel clusters. Expand as your energy demand grows&quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNjOHNwOTJlNjZqb2g1bXp0JTIyJTdEJTJDJTIybm9kZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMnRleHQlMjIlMkMlMjJsZWF2ZXMlMjIlM0ElNUIlN0IlMjJrbGFzcyUyMiUzQSUyMmxlYWYlMjIlMkMlMjJ0ZXh0JTIyJTNBJTIyVGhlJTIwaW52ZXJ0ZXIlMjBzdXBwb3J0cyUyMHBhcmFsbGVsJTIwY29ubmVjdGlvbiUyMHVwJTIwdG8lMjAxMiUyMHVuaXRzJTJDJTIwYW5kJTIwdGhlJTIwYmF0dGVyeSUyMHN1cHBvcnRzJTIwNCUyMHBhcmFsbGVsJTIwY2x1c3RlcnMuJTIwRXhwYW5kJTIwYXMlMjB5b3VyJTIwZW5lcmd5JTIwZGVtYW5kJTIwZ3Jvd3MlMjIlMkMlMjJtYXJrcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIybWFyayUyMiUyQyUyMnR5cGUlMjIlM0ElMjJzeiUyMiUyQyUyMmRhdGElMjIlM0ElN0IlMjJ2YWx1ZSUyMiUzQTEyJTJDJTIyc3pVbml0JTIyJTNBJTIycHQlMjIlN0QlN0QlNUQlN0QlNUQlN0QlNUQlMkMlMjJjb250ZW50VHlwZSUyMiUzQSUyMmNhbmdqaWUtdGV4dGJsb2NrJTIyJTdEJTVEJTdE\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><p><span data-type=\"text\">inverter \u0eaa\u0eb0\u0eab\u0e99\u0eb1\u0e9a\u0eaa\u0eb0\u0eab\u0e99\u0eb9\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e99\u0ec0\u0e96\u0eb4\u0e87 12 \u0eab\u0e99\u0ec8\u0ea7\u0e8d, \u0ec1\u0ea5\u0eb0\u0eab\u0ea1\u0ecd\u0ec9\u0ec4\u0e9f\u0eaa\u0eb0\u0eab\u0e99\u0eb1\u0e9a\u0eaa\u0eb0\u0eab\u0e99\u0eb9\u0e99 4 \u0e81\u0eb8\u0ec8\u0ea1\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e99. \u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e9b\u0e95\u0eb2\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99<\/span><\/p><\/article><\/article><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29a3cd68 e-con-full e-flex e-con e-parent\" data-id=\"29a3cd68\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1798ec77 elementor--h-position-left elementor-widget__width-inherit elementor-hidden-mobile elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"1798ec77\" data-element_type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-3d660c0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87<\/div><div class=\"elementor-slide-description\">\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a, \u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0ea7\u0ebd\u0e99\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0eb0\u0ec3\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0ea7\u0e97\u0eb5 Fsolar.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-c141586 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0ec0\u0ea7\u0ea5\u0eb2 Smart TOU<\/div><div class=\"elementor-slide-description\">\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0e81\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0\u0e9b\u0ec8\u0ead\u0e8d\u0ead\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0ea7\u0ea5\u0eb2\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e9e\u0eb2\u0eaa\u0eb5.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-502dcd6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e9f\u0eb7\u0ec9\u0e99\u0e95\u0ebb\u0ea7 PID \u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0ea7\u0ebd\u0e81<\/div><div class=\"elementor-slide-description\">\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ec1\u0e9c\u0e87\u0ec1\u0eaa\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e8d\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0\u0ec3\u0eab\u0ec9\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-488bbd1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0ead\u0ead\u0e81\u0eaa\u0eb9\u0e99<\/div><div class=\"elementor-slide-description\">\u0ec3\u0eab\u0ec9\u0ec1\u0e99\u0ec8\u0ec3\u0e88\u0ea7\u0ec8\u0eb2\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec0\u0e81\u0eb5\u0e99\u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99\u0eaa\u0eb9\u0ec8\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2.<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\u0e9e\u0eb2\u0e9a\u0e81\u0ec8\u0ead\u0e99\u0eab\u0e99\u0ec9\u0eb2\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0e9b\u0e95\u0ecd\u0ec8\u0ec4\u0e9b\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41de0401 e-grid elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet e-con-boxed e-con e-child\" data-id=\"41de0401\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4afd74e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4afd74e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-34821\" alt=\"4 1 Real Time Monitoring Felicitysolar 16 9.jpg\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-768x432.jpg 768w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-300x169.jpg 300w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-1024x576.jpg 1024w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-1536x864.jpg 1536w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-18x10.jpg 18w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9-600x338.jpg 600w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-1-Real-time-Monitoring-felicitysolar-16-9.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87<\/h3><p class=\"elementor-image-box-description\">\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a, \u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0ea7\u0ebd\u0e99\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0eb0\u0ec3\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0ea7\u0e97\u0eb5 Fsolar.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aeed220 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2aeed220\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-34989\" alt=\"4 2 Tou Felicitysolar 16x9\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-768x432.jpg 768w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-300x169.jpg 300w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-1024x576.jpg 1024w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-1536x864.jpg 1536w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-18x10.jpg 18w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1-600x338.jpg 600w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-2-TOU-felicitysolar-16x9-1.jpg 1600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0ec0\u0ea7\u0ea5\u0eb2 Smart TOU<\/h3><p class=\"elementor-image-box-description\">\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0e81\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0\u0e9b\u0ec8\u0ead\u0e8d\u0ead\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0ea7\u0ea5\u0eb2\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e9e\u0eb2\u0eaa\u0eb5.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467ae2b2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"467ae2b2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-34823\" alt=\"4 3 Pid Felicitysolar 16 9.jpg\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-768x432.jpg 768w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-300x169.jpg 300w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-1024x576.jpg 1024w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-1536x864.jpg 1536w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-18x10.jpg 18w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9-600x338.jpg 600w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-3-PID-felicitysolar-16-9.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e81\u0eb2\u0e99\u0e9f\u0eb7\u0ec9\u0e99\u0e95\u0ebb\u0ea7 PID \u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0ea7\u0ebd\u0e81<\/h3><p class=\"elementor-image-box-description\">\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ec1\u0e9c\u0e87\u0ec1\u0eaa\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e8d\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0\u0ec3\u0eab\u0ec9\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68334423 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"68334423\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-34824\" alt=\"4 4 Zero Export Control Ct Felicitysolar 16 9.jpg\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-768x432.jpg 768w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-300x169.jpg 300w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-1024x576.jpg 1024w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-1536x864.jpg 1536w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-18x10.jpg 18w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9-600x338.jpg 600w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/4-4-Zero-Export-Control-CT-felicitysolar-16-9.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0e81\u0eb2\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0ead\u0ead\u0e81\u0eaa\u0eb9\u0e99<\/h3><p class=\"elementor-image-box-description\">\u0ec3\u0eab\u0ec9\u0ec1\u0e99\u0ec8\u0ec3\u0e88\u0ea7\u0ec8\u0eb2\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec0\u0e81\u0eb5\u0e99\u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99\u0eaa\u0eb9\u0ec8\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d95b746 e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"6d95b746\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5de8a596 elementor--h-position-left elementor-widget__width-inherit elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"5de8a596\" data-element_type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-3d660c0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87<\/div><div class=\"elementor-slide-description\">\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a, \u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0ea7\u0ebd\u0e99\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0eb0\u0ec3\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0e88\u0eb4\u0e87\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0ea7\u0e97\u0eb5 Fsolar.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-c141586 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0ec0\u0ea7\u0ea5\u0eb2 Smart TOU<\/div><div class=\"elementor-slide-description\">\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0e81\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0\u0e9b\u0ec8\u0ead\u0e8d\u0ead\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0ea7\u0ea5\u0eb2\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e9e\u0eb2\u0eaa\u0eb5.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-502dcd6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e9f\u0eb7\u0ec9\u0e99\u0e95\u0ebb\u0ea7 PID \u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0ea7\u0ebd\u0e81<\/div><div class=\"elementor-slide-description\">\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ec1\u0e9c\u0e87\u0ec1\u0eaa\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e8d\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0\u0ec3\u0eab\u0ec9\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-488bbd1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e81\u0eb2\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0ead\u0ead\u0e81\u0eaa\u0eb9\u0e99<\/div><div class=\"elementor-slide-description\">\u0ec3\u0eab\u0ec9\u0ec1\u0e99\u0ec8\u0ec3\u0e88\u0ea7\u0ec8\u0eb2\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec0\u0e81\u0eb5\u0e99\u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99\u0eaa\u0eb9\u0ec8\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2.<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\u0e9e\u0eb2\u0e9a\u0e81\u0ec8\u0ead\u0e99\u0eab\u0e99\u0ec9\u0eb2\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0e9b\u0e95\u0ecd\u0ec8\u0ec4\u0e9b\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a00d51c e-flex e-con-boxed e-con e-parent\" data-id=\"1a00d51c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58c343c8 elementor-widget elementor-widget-heading\" data-id=\"58c343c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e9c\u0ead\u0e94 GEN \u0e97\u0eb5\u0ec8\u0e95\u0eb1\u0ec9\u0e87\u0ec2\u0e9b\u0ea3\u0ec1\u0e81\u0ea3\u0ea1\u0ec4\u0e94\u0ec9. \u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0ec1\u0e9a\u0e9a\u0e8d\u0eb7\u0e94\u0eab\u0e8d\u0eb8\u0ec8\u0e99.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75bb05cb e-con-full e-flex e-con e-child\" data-id=\"75bb05cb\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-7cffeec e-con-full e-flex e-con e-child\" data-id=\"7cffeec\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3480eade elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"3480eade\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-1-genertaor.png\" class=\"attachment-full size-full wp-image-34735\" alt=\"5 1 Genertaor.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-1-genertaor.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-1-genertaor-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0ec2\u0edd\u0e94\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e81\u0ecd\u0eb2\u0ec0\u0e99\u0eb5\u0e94\u0e81\u0eb2\u0e8a\u0ea7\u0e99<\/h3><p class=\"elementor-image-box-description\">\u0eae\u0ead\u0e87\u0eae\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e95\u0eb1\u0ec9\u0e87\u0ec0\u0e81\u0e99\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e9b\u0eb1\u0ec8\u0e99\u0ec4\u0e9f\u0e81\u0eb2\u0e8a\u0ea7\u0e99\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0ec2\u0eab\u0ebc\u0e94\u0ec0\u0e81\u0eb5\u0e99 \u0ec1\u0ea5\u0eb0\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0ec9\u0ead\u0e99\u0ec0\u0e81\u0eb5\u0e99.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4726a7f6 e-con-full e-flex e-con e-child\" data-id=\"4726a7f6\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a3c3e3d elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"4a3c3e3d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-2-Smart-load-mode.png\" class=\"attachment-full size-full wp-image-34739\" alt=\"5 2 Smart Load Mode.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-2-Smart-load-mode.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-2-Smart-load-mode-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0ec2\u0edd\u0e94\u0e81\u0eb2\u0e99\u0ec2\u0eab\u0ebc\u0e94\u0ead\u0eb1\u0e94\u0eaa\u0eb0\u0ea5\u0eb4\u0e8d\u0eb0<\/h3><p class=\"elementor-image-box-description\">\u0ec0\u0e9b\u0eb5\u0e94\u0ec3\u0e8a\u0ec9\u0e81\u0eb2\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0ec2\u0eab\u0ebc\u0e94\u0ead\u0eb1\u0e94\u0eaa\u0eb0\u0ea5\u0eb4\u0e8d\u0eb0\u0ead\u0eb1\u0e94\u0e95\u0eb0\u0ec2\u0e99\u0ea1\u0eb1\u0e94\u0ec2\u0e94\u0e8d\u0ead\u0eb5\u0e87\u0ec3\u0eaa\u0ec8\u0ea5\u0eb0\u0e94\u0eb1\u0e9a SOC \u0e82\u0ead\u0e87\u0ec1\u0e9a\u0eb1\u0e94\u0ec0\u0e95\u0eb5\u0ea3\u0eb5\u0e97\u0eb5\u0ec8\u0e95\u0eb1\u0ec9\u0e87\u0ec4\u0ea7\u0ec9\u0ea5\u0ec8\u0ea7\u0e87\u0edc\u0ec9\u0eb2 \u0eab\u0ebc\u0eb7\u0e95\u0eb2\u0e95\u0eb0\u0ea5\u0eb2\u0e87\u0ec0\u0ea7\u0ea5\u0eb2, \u0e8a\u0ec8\u0ea7\u0e8d\u0e9b\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0\u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e82\u0ead\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0ec3\u0eab\u0ec9\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ce52fff e-con-full e-flex e-con e-child\" data-id=\"3ce52fff\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3457ef6 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"3457ef6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-3-Grid-tied-Inverter-Mode.png\" class=\"attachment-full size-full wp-image-34743\" alt=\"5 3 Grid Tied Inverter Mode.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-3-Grid-tied-Inverter-Mode.png 100w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/5-3-Grid-tied-Inverter-Mode-12x12.png 12w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">\u0ec2\u0edd\u0e94 Inverter \u0ec1\u0e9a\u0e9a\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0e82\u0ec8\u0eb2\u0e8d<\/h3><p class=\"elementor-image-box-description\">\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0e81\u0eb1\u0e9a micro-inverter, \u0e81\u0eb2\u0e99\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0ead\u0e87\u0ec1\u0eaa\u0e87\u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0ec1\u0e9b\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e97\u0eb5\u0ec8\u0eaa\u0ecd\u0eb2\u0e84\u0eb1\u0e99.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1574cbe e-flex e-con-boxed e-con e-parent\" data-id=\"1574cbe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7499b17c elementor-widget-widescreen__width-inherit elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"7499b17c\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\t\t<link id='font-awesome-css' href='https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n}\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option::after{\n  content: \"\";\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  transition: all .3s;\n}\n  #uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option.active::after{\n      backdrop-filter: none;\n      -webkit-backdrop-filter: none;\n  }\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  }\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  }\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n\n\n@media screen and (max-width: 520px) {\n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .active.ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n  \n  \n  \n\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_7499b17c.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n \n  \n  \n \n  \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_7499b17c\" class=\"exp-wrapper\" data-selecteditem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_7499b17c_item1\" class=\"ue_option elementor-repeater-item-a97ce74  active\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-5-supermarket.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Supermarkets\" class=\"ue_label\">\n         \n                           \n                 \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0e8a\u0eb8\u0e9a\u0ec0\u0e9b\u0eb5\u0ea1\u0eb2\u0ec0\u0e81\u0eb1\u0e94<\/div>                             <div class=\"ue_sub\">  <\/div>                                                        <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_7499b17c_item2\" class=\"ue_option elementor-repeater-item-b35f4e9\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-4-factory.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Industrial Parks\" class=\"ue_label\">\n         \n                           \n                 \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0eaa\u0ea7\u0e99\u0ead\u0eb8\u0e94\u0eaa\u0eb2\u0eab\u0eb0\u0e81\u0ecd\u0eb2<\/div>                             <div class=\"ue_sub\">  <\/div>                                                        <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_7499b17c_item3\" class=\"ue_option elementor-repeater-item-12837d8\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-1-hospital.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Hospitals\" class=\"ue_label\">\n         \n                           \n                 \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0ec2\u0eae\u0e87\u0edd\u0ecd<\/div>                             <div class=\"ue_sub\">  <\/div>                                                        <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2878df elementor-widget-widescreen__width-inherit elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"c2878df\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n}\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option::after{\n  content: \"\";\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  transition: all .3s;\n}\n  #uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option.active::after{\n      backdrop-filter: none;\n      -webkit-backdrop-filter: none;\n  }\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  }\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n #uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_content_link{\n     width:100%\n  }\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) .ue_content_link{\n  pointer-events: none;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_content_link.ue_content_link--hover-mode{\n  position: absolute;\n  width: 100%;\n  height: 100%;\n}\n\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  }\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n\n\n@media screen and (max-width: 520px) {\n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .active.ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n  \n  \n  #uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) .ue_content_link{\n    pointer-events: auto;\n  } \n  \n\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_c2878df.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n \n  \n  \n \n  \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_c2878df\" class=\"exp-wrapper\" data-selecteditem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_c2878df_item1\" class=\"ue_option elementor-repeater-item-a97ce74\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-3-hotel.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Hotels\" class=\"ue_label\">\n         \n                           \n         <a class=\"ue_content_link ue_content_link--hover-mode\" href=\"\" ><\/a>        \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0ec2\u0eae\u0e87\u0ec1\u0eae\u0ea1<\/div>                             <div class=\"ue_sub\">  <\/div>                                                        <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_c2878df_item2\" class=\"ue_option elementor-repeater-item-b35f4e9  active\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-2-school.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"School\" class=\"ue_label\">\n         \n                           \n         <a class=\"ue_content_link ue_content_link--hover-mode\" href=\"\" ><\/a>        \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0ec2\u0eae\u0e87\u0eae\u0ebd\u0e99<\/div>                             <div class=\"ue_sub\">  <\/div>                                                        <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-194b0c90 elementor-widget elementor-widget-ucaddon_expanding_content_cards\" data-id=\"194b0c90\" data-element_type=\"widget\" data-widget_type=\"ucaddon_expanding_content_cards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Expanding Content Cards -->\n\n<style>\/* widget: Expanding Content Cards *\/\n\n\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper {\n  box-sizing: border-box;\n  display: flex;\n  flex-direction: row;\n  justify-content: center;\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper{\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options {\n  display: flex;\n  align-items: center;\n  flex-direction: row;\n  justify-content: center;\n  min-width: 200px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option {\n  box-sizing: border-box;\n  display: flex;\n  position: relative;\n  overflow: hidden;\n  cursor: pointer;\n  justify-content: center;\n  background-repeat: no-repeat;\n  background-size: cover;\n}\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option::after{\n  content: \"\";\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  top: 0;\n  left: 0;\n  transition: all .3s;\n}\n  #uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option.active::after{\n      backdrop-filter: none;\n      -webkit-backdrop-filter: none;\n  }\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option.active {\n  flex-grow: 10000;\n}\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) {\n  justify-content: center;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option .ue_shadow {\n  position: absolute;\n  bottom: 0px;\n  left: 0px;\n  right: 0px;\n  height: 100%;\n  z-index:1;\n  transition: 800ms;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_option:not(.active) .ue_label {\n  align-items: center;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option .ue_label {\n  display: flex;\n  z-index:2;\n  }\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option.active .ue_label{\n  animation-name: sub-content-fade;\n}\n@keyframes sub-content-fade{\n  0%   {opacity:0;}\n  80%  {opacity:0;}\n  100% {opacity:1;}\n}\n #uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_content_link{\n     width:100%\n  }\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) .ue_content_link{\n  pointer-events: none;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_content_link.ue_content_link--hover-mode{\n  position: absolute;\n  width: 100%;\n  height: 100%;\n}\n\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option.active .ue_label .ue_info > div {\n  left: 0px;\n  width:100%;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  left: 0px;\n  opacity: 0;\n  width: 0px;\n  height: 0px;\n  transition: width 0ms;\n}\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option .ue_label .ue_info > div {\n  position: relative;\n  }\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper  .ue_options .ue_option .ue_label .ue_info {\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n\n\n@media screen and (max-width: 520px) {\n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .active.ue_option::after{\n  backdrop-filter: none;\n  -webkit-backdrop-filter: none;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options {\n  display: grid;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option{\n    width: 100%;\n}\n  \n  \n  #uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) .ue_content_link{\n    pointer-events: auto;\n  } \n  \n\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_info > div {\n  opacity:1;\n  width:100%;\n  height:auto;\n}\n#uc_expanding_content_cards_elementor_194b0c90.exp-wrapper .ue_options .ue_option:not(.active) .ue_label .ue_sub {\n  height:auto;\n}\n \n \n  \n  \n \n  \n}\n\n<\/style>\n\n<div id=\"uc_expanding_content_cards_elementor_194b0c90\" class=\"exp-wrapper\" data-selecteditem=\"\"  >\n  <div class=\"ue_options uc-items-wrapper\">\n   <div id=\"uc_expanding_content_cards_elementor_194b0c90_item1\" class=\"ue_option elementor-repeater-item-a97ce74\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-5-supermarket.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Supermarket\" class=\"ue_label\">\n         \n                           \n         <a class=\"ue_content_link ue_content_link--hover-mode\" href=\"\" ><\/a>        \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0eaa\u0eb1\u0e9a\u0e9e\u0eb0\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2<\/div>                       <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_194b0c90_item2\" class=\"ue_option elementor-repeater-item-b35f4e9  active\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-4-factory.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Factory\" class=\"ue_label\">\n         \n                           \n         <a class=\"ue_content_link ue_content_link--hover-mode\" href=\"\" ><\/a>        \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0ec2\u0eae\u0e87\u0e87\u0eb2\u0e99<\/div>                       <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n<div id=\"uc_expanding_content_cards_elementor_194b0c90_item3\" class=\"ue_option elementor-repeater-item-e8cdabe\" style=\"background-image:url(https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/6-1-hospital.jpg);\">\n\t        <div class=\"ue_shadow\"><\/div>\t        <div id=\"Hospital\" class=\"ue_label\">\n         \n                           \n         <a class=\"ue_content_link ue_content_link--hover-mode\" href=\"\" ><\/a>        \n                 \n           <div class=\"ue_info\">\n            <div class=\"ue_main\">\u0ec2\u0eae\u0e87\u0edd\u0ecd<\/div>                       <\/div>\n        \n                \n              <\/div>\n      \n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Expanding Content Cards -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fc1e06b e-flex e-con-boxed e-con e-parent\" data-id=\"3fc1e06b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6575f136 elementor-widget elementor-widget-heading\" data-id=\"6575f136\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e88\u0ecd\u0eb2\u0ec0\u0e9e\u0eb2\u0eb0\u0e82\u0ead\u0e87\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-441958a1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"441958a1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c67a2 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"d4c67a2\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;end&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"223111074\" aria-label=\"\u0ec1\u0e97\u0eb1\u0e9a. \u0ec0\u0e9b\u0eb5\u0e94\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e81\u0eb0\u0ea5\u0eb8\u0e99\u0eb2\u0ec3\u0eaa\u0ec8\u0eab\u0ebc\u0eb7\u0e8a\u0ec8\u0ead\u0e87, \u0e9b\u0eb4\u0e94\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0eab\u0ea5\u0ebb\u0e9a\u0eab\u0e99\u0eb5\u0ec1\u0ea5\u0eb0\u0e99\u0ecd\u0eb2\u0e97\u0eb2\u0e87\u0ec2\u0e94\u0e8d\u0ec3\u0e8a\u0ec9\u0e9b\u0eb8\u0ec8\u0ea1\u0ea5\u0eb9\u0e81\u0eaa\u0ead\u0e99.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2231110741\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2231110741\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tIVGM125KHP3G1\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2231110742\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2231110742\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tFLH48314UG1\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2231110741\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2231110741\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-4e271345 e-con-full e-flex e-con e-child\" data-id=\"4e271345\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-18fb3e47 e-grid e-con-full e-con e-child\" data-id=\"18fb3e47\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b505995 elementor-widget elementor-widget-icon-box\" data-id=\"6b505995\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec9\u0ead\u0e99\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0eab\u0ea1\u0ecd\u0ec9\u0ec4\u0e9f\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLFP (LiFePO4)<br>\n160-1000Vdc<br>\n2 \u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8\u0e9b\u0ec9\u0ead\u0e99\u0e82\u0ead\u0e87\u0eab\u0ea1\u0ecd\u0ec9\u0ec4\u0e9f<br>\n\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94. \u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0eaa\u0eb2\u0e81\u0ec4\u0e9f: 120+120(A)<br>\n\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94. \u0e81\u0eb2\u0e99\u0e9b\u0ebb\u0e94\u0e9b\u0ec8\u0ead\u0e8d: 120+120(A)\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53e2f532 elementor-widget elementor-widget-icon-box\" data-id=\"53e2f532\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPVString Input Data\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 250kW. DC Input Power<br>\n\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 1000Vdc. DC Input Voltage<br>\n10 MPP Trackers<br>\n2 \u0eaa\u0eb2\u0e8d\u0e95\u0ecd\u0ec8\u0e95\u0ebb\u0ea7\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1 MPP\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-501641a4 elementor-widget elementor-widget-icon-box\" data-id=\"501641a4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tACInput\/Output Data\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 ACInput\/Output \u0ea5\u0eb0\u0e94\u0eb1\u0e9a 125kW<br>\n\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 137kVA. AC Input\/Output Power<br>\n220\/380,230\/400 Vac (-20%~+15%)<br>\n50\/60 Hz (45 ~ 55 Hz \/ 55 ~ 65 Hz)<br>\n3L+N+PE\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d4182d0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d4182d0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2501a370 e-grid e-con-full e-con e-child\" data-id=\"2501a370\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb262e elementor-widget elementor-widget-icon-box\" data-id=\"6fb262e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0ead\u0e94\u0ec4\u0e9e\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIEC 61727, IEC 62116, CEI 0-21, EN 50549, NRS 097, RD 140, UNE 217002, OVE-Richtlinie R25, G99, VDE-AR-N 4110\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-873dc82 elementor-widget elementor-widget-icon-box\" data-id=\"873dc82\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0ead\u0e94\u0ec4\u0e9e EMC\/\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99: IEC61000-6-2\/4, CEI0-16\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c481f8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"73c481f8\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36be727 e-grid e-con-full e-con e-child\" data-id=\"36be727\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c105875 elementor-widget elementor-widget-icon-box\" data-id=\"c105875\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIP66<br>\n-40 \u0eab\u0eb2 60 \u0ead\u0ebb\u0e87\u0eaa\u0eb2 C (&gt; 45 \u0ead\u0ebb\u0e87\u0eaa\u0eb2 Cderating)<br>\nRS485 \/ Can<br>\n\u0e95\u0eb4\u0e94\u0e9d\u0eb2<br>\nWIFI\/Bluetooth\/4G\/LAN(\u0e97\u0eb2\u0e87\u0ec0\u0ea5\u0eb7\u0ead\u0e81)<br>\n\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 12 \u0ec3\u0e99\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e99<br>\n\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e81\u0eb1\u0e99 10 \u0e9b\u0eb5\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45d08269 elementor-widget elementor-widget-icon-box\" data-id=\"45d08269\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t-\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0eaa\u0eb8\u0e94\u0e97\u0eb4: 156kg\n<br>\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0ea5\u0ea7\u0ea1: 200kg<br>\n\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99: 1271*814.5*379.5mm<br>\n\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e9a\u0eb1\u0e99\u0e88\u0eb8: 1410*960*646mm\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2231110742\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2231110742\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-4cecc4ca e-con-full e-flex e-con e-child\" data-id=\"4cecc4ca\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-71fe32d7 e-grid e-con-full e-con e-child\" data-id=\"71fe32d7\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e215d45 elementor-widget elementor-widget-icon-box\" data-id=\"2e215d45\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e9e\u0eb0\u0e8d\u0eb2\u0e81\u0ead\u0e99\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t16.07kWh | 51.2V | 314 \u0ead<br>LiFePO4<br>DOD: 90%\n\u0ec0\u0e96\u0eb4\u0e87 15 \u0eab\u0e99\u0ec8\u0ea7\u0e8d\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e99 (225kWh)\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5843b82c elementor-widget elementor-widget-icon-box\" data-id=\"5843b82c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e88\u0ecd\u0eb2\u0ec0\u0e9e\u0eb2\u0eb0\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIP20<br>&gt; 8000 \u0eae\u0ead\u0e9a<br>\u0e81\u0eb2\u0e99\u0ea7\u0eb2\u0e87\u0ec2\u0ea1\u0e94\u0eb9\u0e99<br>RS485\/CAN\/Enthernet\/WiFi(2.4G)<br>Built-in Smart BMS, MCCB \u0ea1\u0eb5\u0e9f\u0eb1\u0e87\u0e8a\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87 shunt, Fuse\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5175fe elementor-widget elementor-widget-icon-box\" data-id=\"7f5175fe\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e81\u0eb2\u0e99\u0ea2\u0eb1\u0ec9\u0e87\u0ea2\u0eb7\u0e99\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCE\/IEC 62619\/IEC62040\/UN38.3\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-554e24d6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"554e24d6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77647252 e-grid e-con-full e-con e-child\" data-id=\"77647252\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b03f5b6 elementor-widget elementor-widget-icon-box\" data-id=\"b03f5b6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0ec2\u0ea1\u0e94\u0eb9\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99: 28.8KG<br>\n\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0e8a\u0eb8\u0e94: 42.2KG<br>\n\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99: 780x525.4x180MM<br>\n\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e9a\u0eb1\u0e99\u0e88\u0eb8: 890x602x333MM\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254e0b43 elementor-widget elementor-widget-icon-box\" data-id=\"254e0b43\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0ec2\u0ea1\u0e94\u0eb9\u0e99\u0eab\u0ea1\u0ecd\u0ec9\u0ec4\u0e9f\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99: 127.2KG<br>\n\u0e99\u0ec9\u0ecd\u0eb2\u0eab\u0e99\u0eb1\u0e81\u0e8a\u0eb8\u0e94: 146.5KG<br>\n\u0e82\u0eb0\u0eab\u0e99\u0eb2\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99: 819.5x525.4x260MM<br>\n\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e9a\u0eb1\u0e99\u0e88\u0eb8: 925x560x405MM<br>\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a\u0ec1\u0e9a\u0eb1\u0e94\u0ec0\u0e95\u0eb5\u0ea3\u0eb5: IFpP74\/176\/120\/[1P16S]E\/-20+50\/90\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-431f982d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"431f982d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e0c3d1d e-grid e-con-full e-con e-child\" data-id=\"7e0c3d1d\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21acb46d elementor-widget elementor-widget-icon-box\" data-id=\"21acb46d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0e81\u0eb2\u0e99\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e81\u0eb1\u0e99\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t10 \u0e9b\u0eb5\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-250264a0 e-con-full e-flex e-con e-parent\" data-id=\"250264a0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-4d8da157 e-con-full e-flex e-con e-child\" data-id=\"4d8da157\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ebc7747 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6ebc7747\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0eaa\u0ec9\u0eb2\u0e87\u0e82\u0eb6\u0ec9\u0e99\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87. \u0e9e\u0ec9\u0ead\u0ea1\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e82\u0eb0\u0edc\u0eb2\u0e94.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24946a83 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"24946a83\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article class=\"4ever-article\" data-clipboard-cangjie=\"[&quot;root&quot;,{},[&quot;p&quot;,{&quot;uuid&quot;:&quot;mnsira7vd2ma4e3t93&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;text&quot;},[&quot;span&quot;,{&quot;data-type&quot;:&quot;leaf&quot;},&quot;Explore the System&quot;]]]]\" data-identifier-application__slash__x-cangjie-fragment=\"JTdCJTIya2xhc3MlMjIlM0ElMjJkb2N1bWVudCUyMiUyQyUyMmRhdGElMjIlM0ElN0IlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIyYmxvY2slMjIlMkMlMjJ0eXBlJTIyJTNBJTIycGFyYWdyYXBoJTIyJTJDJTIyZGF0YSUyMiUzQSU3QiUyMnV1aWQlMjIlM0ElMjJtbnNpcmE3dmQybWE0ZTN0OTMlMjIlN0QlMkMlMjJub2RlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIydGV4dCUyMiUyQyUyMmxlYXZlcyUyMiUzQSU1QiU3QiUyMmtsYXNzJTIyJTNBJTIybGVhZiUyMiUyQyUyMnRleHQlMjIlM0ElMjJFeHBsb3JlJTIwdGhlJTIwU3lzdGVtJTIyJTJDJTIybWFya3MlMjIlM0ElNUIlNUQlN0QlNUQlN0QlNUQlMkMlMjJjb250ZW50VHlwZSUyMiUzQSUyMmNhbmdqaWUtdGV4dGJsb2NrJTIyJTdEJTVEJTdE\" data-identifier-application__slash__x-doc-key=\"4maOgXb7gDr88lWN\"><p><span data-type=\"text\">\u0eaa\u0eb3\u0eab\u0ebc\u0ea7\u0e94\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e94\u0ec9\u0ea7\u0e8d<\/span><\/p><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77c2794a e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"77c2794a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:400,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23238207 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"23238207\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pop\" href=\"https:\/\/eu.felicitysolar.com\/la\/product\/ivgm75-125kw-p3g1\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">IVGM125KHP3G1<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c051dd5 elementor-widget elementor-widget-button\" data-id=\"7c051dd5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pop\" href=\"https:\/\/eu.felicitysolar.com\/la\/product\/flh48314ug1\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FLH48314UG1<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24f9f459 e-con-full e-flex e-con e-child\" data-id=\"24f9f459\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a148b15 elementor-widget elementor-widget-image\" data-id=\"a148b15\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery.png\" class=\"attachment-large size-large wp-image-34794\" alt=\"8 1 Inverter And Battery.png\" srcset=\"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery.png 800w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-300x300.png 300w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-150x150.png 150w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-768x768.png 768w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-12x12.png 12w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-600x600.png 600w, https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2026\/04\/8-1-inverter-and-battery-100x100.png 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e81\u0eb2\u0e99\u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 125kW C&amp;I \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec4\u0e94\u0ec9. Reliable. \u0eaa\u0ec9\u0eb2\u0e87\u0e82\u0eb6\u0ec9\u0e99\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eaa\u0eb9\u0e87. Built for High-power Applications Flexible system design with dual battery inputs and 10-channel solar charge controllers for stable high-power operation. 257kWh per Cluster 2x Independent Battery Inputs 1.5MW Scalable Power 98.688MWh Expandable Capacity 16 Clusters in Parallel 0ms Seamless Switching With ultra-fast switching capability, [\u2026]<\/p>","protected":false},"author":3,"featured_media":34678,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-34677","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"rankMath":{"parentDomain":"felicitysolar.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"125kw-ci-energy-storage-solution-2026","permalinkFormat":"https:\/\/eu.felicitysolar.com\/la\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/eu.felicitysolar.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"CRM","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":[],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/eu.felicitysolar.com\/la","objectID":34677,"objectType":"post","locale":"lo","localeFull":"lo","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/www\/wwwroot\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"icon gif","url":"https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/www\/wwwroot\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Feu.felicitysolar.com%2Fla&r=https%3A%2F%2Feu.felicitysolar.com%3A88%2Fla%2Fwp-json%2Fwp%2Fv2%2Fpages%2F34677%3Fnonce%3Da5d5c71c70","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/eu.felicitysolar.com\/wp-content\/uploads\/2025\/02\/\u7f51\u7ad9-Favicon.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/eu.felicitysolar.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":[],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitith% %PAPAVEP3T %sEP% 1TP12TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3TP3T","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/pages\/34677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/comments?post=34677"}],"version-history":[{"count":26,"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/pages\/34677\/revisions"}],"predecessor-version":[{"id":36523,"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/pages\/34677\/revisions\/36523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/media\/34678"}],"wp:attachment":[{"href":"https:\/\/eu.felicitysolar.com\/la\/wp-json\/wp\/v2\/media?parent=34677"}],"curies":[{"name":"\u0e81\u0eb2\u0e99","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}